{"id":6456,"date":"2025-05-27T06:35:00","date_gmt":"2025-05-27T06:35:00","guid":{"rendered":"https:\/\/topshelfcbd.nl\/shop\/senza-categoria\/weneedweed-pineapple-express-hq-fiori\/"},"modified":"2025-05-27T06:35:00","modified_gmt":"2025-05-27T06:35:00","slug":"weneedweed-pineapple-express-hq-fiori","status":"publish","type":"product","link":"https:\/\/topshelfcbd.nl\/it\/shop\/infiorescenze-cbd\/weneedweed-pineapple-express-hq-fiori\/","title":{"rendered":"Weneedweed &#8211; Pineapple Express HQ+ fiori"},"content":{"rendered":"<h2 class=\"x_p1\">Ananas Express<\/h2>\n<p>Una variet\u00e0 molto popolare non solo per i suoi effetti ma anche per il suo gusto e l&#8217;odore molto esuberante, una vera variet\u00e0 all in one! Questa variet\u00e0 \u00e8 stata creata incrociando il ceppo trainwreck e l&#8217;hawaiian CBD con un rapporto 60:40 sativa\/indica. Il sapore \u00e8 meglio descritto come quello dell&#8217;ananas dolce con note di pino e cannella, grazie alla presenza dei terpeni mircene, limonene, beta-cariofillene con livelli eccezionalmente alti di guaiolo e terpinolene. Davvero unica e amata da molti. Le sue proporzioni gradevoli la rendono una variet\u00e0 perfetta per le attivit\u00e0 sociali e quotidiane. Per scoprire cosa pu\u00f2 fare per te questa variet\u00e0, ti consigliamo di fare una ricerca personale, poich\u00e9 non siamo autorizzati a fare affermazioni mediche.     <\/p>\n<p><strong>I fiori TopshelfCBD sono completamente certificati e testati dall&#8217;UE, dal seme al prodotto finito. I fiori sono coltivati biologicamente al 100% in casa e selezionati a mano, lavorati e accuratamente essiccati e purificati. Quindi questo prodotto \u00e8 davvero di qualit\u00e0 Topshelf ed \u00e8 anche una delizia per i buongustai.    <\/strong><\/p>\n<p>Inoltre, a meno di <strong>4,50 euro al grammo<\/strong>, i nostri fiori sono tra i migliori sul mercato in termini di rapporto qualit\u00e0\/prezzo, il che li rende <span style=\"font-size: medium;\">una meravigliosa base pulita per produrre il tuo olio di CBD, la tua crema di CBD o gli edibili di CBD di altissima qualit\u00e0. <\/span> <\/p>\n<p><strong>I fiori sono disponibili in qualit\u00e0 popcorn (fiori piccoli) e Connaisseur (fiori grandi) per i veri buongustai.<\/strong><\/p>\n<p><strong>Fiori TopshelfCBD:<\/strong><\/p>\n<ol>\n<li><strong>Qualit\u00e0 pluripremiata!<\/strong>  Fiori di CBD basati su genetiche di CBD coltivate in modo specifico con l&#8217;effetto pi\u00f9 bello e con un contenuto di terpeni naturali molto elevato (niente canapa industriale)<\/li>\n<li><strong>Unico! 100% tracciabile e trasparente! <\/strong>  Massima qualit\u00e0, testata e certificata dal seme al fiore, produzione completamente interna, nessuna biomassa di terzi di cui spesso non \u00e8 possibile rintracciare l&#8217;origine. I numeri di lotto di tutti i nostri t\u00e8 e fiori sono riportati sulla confezione. <\/li>\n<li><strong>Sostenibilit\u00e0!<\/strong>  Tutti i nostri prodotti sono realizzati in modo responsabile, 100% biologico, nel rispetto della terra e senza influenze di terzi, in modo da poter lavorare a tutto tondo per offrirti ci\u00f2 che meriti.<\/li>\n<li>Solo i fiori <strong>pi\u00f9<\/strong> belli sono sufficienti per il nostro marchio, ovvero: coltivazione indoor con le migliori condizioni climatiche, illuminazione a LED (calore minimo), idroponica, senza sostanze chimiche, senza agenti patogeni, senza metalli pesanti, attraverso un terreno pulito e testato, senza rami e altre parti contenenti bassi livelli di sostanze attive.<\/li>\n<li><strong>La base ideale per realizzare i tuoi prodotti a base di CBD monorigine<\/strong>, come olio di CBD, unguento di CBD, edibili di CBD, con una composizione molto ricca di cannabidoidi\/terpeni\/flavonoidi.<\/li>\n<\/ol>\n<p><strong>I fiori di CBD sono perfetti per:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/topshelfcbd.nl\/zelf-cbd-olie-maken\/\" target=\"_blank\" rel=\"noopener\">Preparare il proprio olio di CBD<\/a><\/li>\n<li><a href=\"https:\/\/topshelfcbd.nl\/zelf-cbd-zalf-maken\/\" target=\"_blank\" rel=\"noopener\">Crea il tuo unguento al CBD<\/a><\/li>\n<li><a href=\"https:\/\/topshelfcbd.nl\/zelf-cbd-edibles-maken-de-basis\/\" target=\"_blank\" rel=\"noopener\">Preparare gli edibili a base di CBD<\/a><\/li>\n<li><a href=\"https:\/\/topshelfcbd.nl\/zelf-cbd-hasj-maken\/\" target=\"_blank\" rel=\"noopener\">Crea il tuo hashish al CBD<\/a><\/li>\n<li><a href=\"https:\/\/topshelfcbd.nl\/verdampen-met-een-vaporizer\/\" target=\"_blank\" rel=\"noopener\">Vaporizzare con un vaporizzatore<\/a><\/li>\n<li><a href=\"https:\/\/topshelfcbd.nl\/hennep-als-tabaksvervanger\/\" target=\"_blank\" rel=\"noopener\">Sostituto del tabacco<\/a><\/li>\n<li><a href=\"https:\/\/topshelfcbd.nl\/cbd-thee-maken\/\" target=\"_blank\" rel=\"noopener\">T\u00e8 al CBD<\/a> (0,25 &#8211; 0,5 gr per tazza)<\/li>\n<\/ul>\n<p><strong>Se sei interessato a offrire questa qualit\u00e0 come rivenditore o ad acquistare all&#8217;ingrosso, contattaci all&#8217;indirizzo info@topshelfcbd.nl.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"cl-preview-section\" data-read-aloud-multi-block=\"true\"><em><strong>Caratteristiche TopshelfCBD Pineapple Express:<\/strong><\/em><\/div>\n<ul>\n<li><em><strong>Aromi esotici di ananas, pino e cannella<\/strong><\/em><\/li>\n<li><em><strong>Struttura compatta, sovraccarica di resina<\/strong><\/em><\/li>\n<li><em><strong>Estremamente saporito e profumato<\/strong><\/em><\/li>\n<li><em><strong>Contenuto di CBD: &gt;20%, &lt; 0,2% di THC<\/strong><\/em><\/li>\n<li><em><strong>100% coltivato in casa<\/strong><\/em><\/li>\n<li><em><strong>Il miglior rapporto qualit\u00e0-prezzo possibile, mai cos\u00ec conveniente!<\/strong><\/em><\/li>\n<li><em><strong>100% conforme all&#8217;UE, certificato e legale<\/strong><\/em><\/li>\n<\/ul>\n<p>Tutti gli ordini effettuati prima delle 14:00 (dal luned\u00ec al venerd\u00ec) saranno spediti il giorno stesso e arriveranno nei giorni lavorativi successivi.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[748],"product_tag":[],"class_list":["post-6456","product","type-product","status-publish","product_cat-infiorescenze-cbd","first","instock","sale","featured","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weneedweed - Pineapple Express HQ+ fiori - Topshelf CBD | Topkwaliteit CBD producten<\/title>\n<meta name=\"description\" content=\"I nostri premiati fiori di CBD sono di altissima qualit\u00e0, coltivati al chiuso, disponibili in 2 formati e alla portata di tutti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/topshelfcbd.nl\/it\/shop\/infiorescenze-cbd\/weneedweed-pineapple-express-hq-fiori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weneedweed - Pineapple Express HQ+ fiori - Topshelf CBD | Topkwaliteit CBD producten\" \/>\n<meta property=\"og:description\" content=\"I nostri premiati fiori di CBD sono di altissima qualit\u00e0, coltivati al chiuso, disponibili in 2 formati e alla portata di tutti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/topshelfcbd.nl\/it\/shop\/infiorescenze-cbd\/weneedweed-pineapple-express-hq-fiori\/\" \/>\n<meta property=\"og:site_name\" content=\"Topshelf CBD | Topkwaliteit CBD producten\" \/>\n<meta property=\"og:image\" content=\"https:\/\/topshelfcbd.nl\/wp-content\/uploads\/2025\/05\/Pineapple-Express-TopshelfCBD.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/topshelfcbd.nl\\\/it\\\/shop\\\/infiorescenze-cbd\\\/weneedweed-pineapple-express-hq-fiori\\\/\",\"url\":\"https:\\\/\\\/topshelfcbd.nl\\\/it\\\/shop\\\/infiorescenze-cbd\\\/weneedweed-pineapple-express-hq-fiori\\\/\",\"name\":\"Weneedweed - Pineapple Express HQ+ fiori - Topshelf CBD | Topkwaliteit CBD producten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/topshelfcbd.nl\\\/it\\\/#website\"},\"datePublished\":\"2025-05-27T06:35:00+00:00\",\"description\":\"I nostri premiati fiori di CBD sono di altissima qualit\u00e0, coltivati al chiuso, disponibili in 2 formati e alla portata di tutti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/topshelfcbd.nl\\\/it\\\/shop\\\/infiorescenze-cbd\\\/weneedweed-pineapple-express-hq-fiori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/topshelfcbd.nl\\\/it\\\/shop\\\/infiorescenze-cbd\\\/weneedweed-pineapple-express-hq-fiori\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/topshelfcbd.nl\\\/it\\\/shop\\\/infiorescenze-cbd\\\/weneedweed-pineapple-express-hq-fiori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/topshelfcbd.nl\\\/it\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/topshelfcbd.nl\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Weneedweed &#8211; Pineapple Express HQ+ fiori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/topshelfcbd.nl\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/topshelfcbd.nl\\\/it\\\/\",\"name\":\"Topshelf CBD | Topkwaliteit CBD producten\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/topshelfcbd.nl\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/topshelfcbd.nl\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/topshelfcbd.nl\\\/it\\\/#organization\",\"name\":\"Topshelf CBD | Topkwaliteit CBD producten\",\"url\":\"https:\\\/\\\/topshelfcbd.nl\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/topshelfcbd.nl\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/topshelfcbd.nl\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo-TopshelfCBD-3-e1748330464966-768x244-1.webp\",\"contentUrl\":\"https:\\\/\\\/topshelfcbd.nl\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo-TopshelfCBD-3-e1748330464966-768x244-1.webp\",\"width\":767,\"height\":244,\"caption\":\"Topshelf CBD | Topkwaliteit CBD producten\"},\"image\":{\"@id\":\"https:\\\/\\\/topshelfcbd.nl\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weneedweed - Pineapple Express HQ+ fiori - Topshelf CBD | Topkwaliteit CBD producten","description":"I nostri premiati fiori di CBD sono di altissima qualit\u00e0, coltivati al chiuso, disponibili in 2 formati e alla portata di tutti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/topshelfcbd.nl\/it\/shop\/infiorescenze-cbd\/weneedweed-pineapple-express-hq-fiori\/","og_locale":"it_IT","og_type":"article","og_title":"Weneedweed - Pineapple Express HQ+ fiori - Topshelf CBD | Topkwaliteit CBD producten","og_description":"I nostri premiati fiori di CBD sono di altissima qualit\u00e0, coltivati al chiuso, disponibili in 2 formati e alla portata di tutti.","og_url":"https:\/\/topshelfcbd.nl\/it\/shop\/infiorescenze-cbd\/weneedweed-pineapple-express-hq-fiori\/","og_site_name":"Topshelf CBD | Topkwaliteit CBD producten","og_image":[{"width":1080,"height":1080,"url":"https:\/\/topshelfcbd.nl\/wp-content\/uploads\/2025\/05\/Pineapple-Express-TopshelfCBD.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/topshelfcbd.nl\/it\/shop\/infiorescenze-cbd\/weneedweed-pineapple-express-hq-fiori\/","url":"https:\/\/topshelfcbd.nl\/it\/shop\/infiorescenze-cbd\/weneedweed-pineapple-express-hq-fiori\/","name":"Weneedweed - Pineapple Express HQ+ fiori - Topshelf CBD | Topkwaliteit CBD producten","isPartOf":{"@id":"https:\/\/topshelfcbd.nl\/it\/#website"},"datePublished":"2025-05-27T06:35:00+00:00","description":"I nostri premiati fiori di CBD sono di altissima qualit\u00e0, coltivati al chiuso, disponibili in 2 formati e alla portata di tutti.","breadcrumb":{"@id":"https:\/\/topshelfcbd.nl\/it\/shop\/infiorescenze-cbd\/weneedweed-pineapple-express-hq-fiori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/topshelfcbd.nl\/it\/shop\/infiorescenze-cbd\/weneedweed-pineapple-express-hq-fiori\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/topshelfcbd.nl\/it\/shop\/infiorescenze-cbd\/weneedweed-pineapple-express-hq-fiori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/topshelfcbd.nl\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/topshelfcbd.nl\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Weneedweed &#8211; Pineapple Express HQ+ fiori"}]},{"@type":"WebSite","@id":"https:\/\/topshelfcbd.nl\/it\/#website","url":"https:\/\/topshelfcbd.nl\/it\/","name":"Topshelf CBD | Topkwaliteit CBD producten","description":"","publisher":{"@id":"https:\/\/topshelfcbd.nl\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/topshelfcbd.nl\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/topshelfcbd.nl\/it\/#organization","name":"Topshelf CBD | Topkwaliteit CBD producten","url":"https:\/\/topshelfcbd.nl\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/topshelfcbd.nl\/it\/#\/schema\/logo\/image\/","url":"https:\/\/topshelfcbd.nl\/wp-content\/uploads\/2025\/06\/cropped-logo-TopshelfCBD-3-e1748330464966-768x244-1.webp","contentUrl":"https:\/\/topshelfcbd.nl\/wp-content\/uploads\/2025\/06\/cropped-logo-TopshelfCBD-3-e1748330464966-768x244-1.webp","width":767,"height":244,"caption":"Topshelf CBD | Topkwaliteit CBD producten"},"image":{"@id":"https:\/\/topshelfcbd.nl\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/topshelfcbd.nl\/it\/wp-json\/wp\/v2\/product\/6456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/topshelfcbd.nl\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/topshelfcbd.nl\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/topshelfcbd.nl\/it\/wp-json\/wp\/v2\/comments?post=6456"}],"wp:attachment":[{"href":"https:\/\/topshelfcbd.nl\/it\/wp-json\/wp\/v2\/media?parent=6456"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/topshelfcbd.nl\/it\/wp-json\/wp\/v2\/product_brand?post=6456"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/topshelfcbd.nl\/it\/wp-json\/wp\/v2\/product_cat?post=6456"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/topshelfcbd.nl\/it\/wp-json\/wp\/v2\/product_tag?post=6456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}